{"id":14868,"date":"2026-07-01T06:43:44","date_gmt":"2026-07-01T04:43:44","guid":{"rendered":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/?page_id=14868"},"modified":"2026-07-01T06:43:47","modified_gmt":"2026-07-01T04:43:47","slug":"actualites-des-labomaths-de-lacademie-de-nice-1er-semestre-2025-2026","status":"publish","type":"page","link":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/actualites-des-labomaths-de-lacademie-de-nice-1er-semestre-2025-2026\/","title":{"rendered":"Actualit\u00e9s des labomaths de l\u2019acad\u00e9mie de Nice 1er semestre 2025-2026"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#88C4DD\u00a0\u00bb width=\u00a0\u00bb95%\u00a0\u00bb custom_margin=\u00a0\u00bb-40px||-30px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb10px|10px||10px|false|true\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_delay=\u00a0\u00bb450ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb33%\u00a0\u00bb border_radii=\u00a0\u00bbon|14px|14px|14px|14px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_color_all=\u00a0\u00bb#B3B3B3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<pre style=\"text-align: center;\"><span style=\"color: #000080; font-size: 24pt;\">Les labomaths<\/span><\/pre>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<pre style=\"text-align: center;\"><a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-labomaths-de-lacademie-de-nice-2025-2026\/' class='small-button smallblue'><span style=\"font-size: 12pt;\"><em>Les labomaths - c'est qui ?<\/em><\/span><\/a>\n<a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/laboratoires-et-clubs\/\/\/' class='small-button smallblue'><span style=\"font-size: 12pt;\"><em>Actualit\u00e9s des labomaths<\/em><\/span><\/a><\/pre>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<pre style=\"text-align: center;\"><span style=\"color: #000080; font-size: 24pt;\">Les clubs maths<\/span><\/pre>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<pre style=\"text-align: center;\"><a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-clubs-maths-de-lacademie-de-nice-2025-2026\/' class='small-button smallblue'><span style=\"font-size: 12pt;\"><em>Les clubs maths c'est qui ?\n<\/em><\/span><\/a> \n<a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/actualites-des-clubs-de-maths-de-lacademie\/' class='small-button smallblue'><span style=\"font-size: 12pt;\"><em>Actualit\u00e9s des clubs<\/em><\/span><\/a>\n<\/pre>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-40px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2>&nbsp;<\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #000080;\">Actualit\u00e9s des labomaths de l\u2019acad\u00e9mie de Nice<\/span><\/h2>\n<h1 id=\"\ud83e\uddee-LaboClubMaths-\u2013-1er-semestre-2025-2026\" class=\"\" style=\"text-align: center;\"><span style=\"font-size: 18pt; color: #000080;\">1er semestre 2025-2026<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#e2e2e2&Prime; custom_margin=\u00a0\u00bb-30px|20px||20px|false|true\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb border_radii=\u00a0\u00bbon|62px|62px|62px|62px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||-41px||false|false\u00a0\u00bb collapsed=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#0DA0C5&Prime; max_width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb border_color_all=\u00a0\u00bb#0C71C3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #000080;\"><strong>Animation des labomaths et des clubs maths de l\u2019acad\u00e9mie &#8211;<\/strong><\/span><span style=\"font-size: 14pt; color: #000080;\"> 2026<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2 id=\"Compte-rendu-r\u00e9union-du-15-janvier-\u2013-Imath-Toulon\" class=\"\"><span style=\"color: #000080; font-size: 14pt;\">Compte rendu r\u00e9union du 15 janvier \u2013 Imath Toulon<\/span><\/h2>\n<p>32 professeur.es pr\u00e9sent.es \/ une dizaine de repr\u00e9sentants du laboratoire de recherche Imath \/ Pierre Mari et Arnaud Lath\u00e9lize pour les IA-IPR de math\u00e9matiques.<\/p>\n<p>L\u2019expos\u00e9 de Gloria Faccannoni nous a replong\u00e9 dans nos \u00e9tudes de math\u00e9matiques avec de bons rappels sur le calcul num\u00e9rique notamment au travers des sch\u00e9mas num\u00e9riques. Elle nous a permis de d\u00e9couvrir en d\u00e9tail de probl\u00e8me de la courbe du chien et le lien avec l\u2019\u00e9nigme des 4 scarab\u00e9es de Gardner. Pour retrouver tous les d\u00e9tails de sa pr\u00e9sentation ainsi que ses conseils de lecture, vous pourrez trouver ses slides sur sa page personnelle <a href=\"https:\/\/faccanoni.univ-tln.fr\/vulgarisation.html\" target=\"_blank\" rel=\"noopener\">https:\/\/faccanoni.univ-tln.fr\/vulgarisation.html<\/a><br \/>Les codes python qu\u2019elle a pr\u00e9sent\u00e9s sont disponibles sur demande.<\/p>\n<p>Nous avons ensuite fait un point sur la g\u00e9ographie\/r\u00e9partition des labomaths\/clubs maths et j\u2019ai insist\u00e9 sur la n\u00e9cessit\u00e9 de bien se r\u00e9f\u00e9rencer via Adage.<\/p>\n<p>Pour les clubs maths, c\u2019etait d\u00e9j\u00e0 possible depuis deux ans mais il y a une nouveaut\u00e9s pour cette ann\u00e9e et pour les coll\u00e8ges UNIQUEMENT c\u2019est un appel d\u2019offre qui s\u2019appelle COOLAB.<br \/>Est venu alors le temps des \u00e9changes et des t\u00e9moignages d\u2019exp\u00e9riences avec de belles id\u00e9es pour la semaine des maths.<\/p>\n<p>Toutes les informations dans le diaporama disponible dans le nuage ci-apr\u00e8s.<br \/><a href=\"https:\/\/nuage03.apps.education.fr\/index.php\/s\/Fem7yC9JezMSiSE\" target=\"_blank\" rel=\"noopener\">https:\/\/nuage03.apps.education.fr\/index.php\/s\/Fem7yC9JezMSiSE<\/a><br \/>Et pour les bonnes id\u00e9es \u00e0 la fin de cette page !!<\/p>\n<p>Une apr\u00e8s-midi qui a permis de cr\u00e9er des nouveaux liens avec l\u2019universit\u00e9 de Toulon \u00e0 destination des professeurs du Var. Un contact \u00e0 privil\u00e9gier pour tous Denis Guicheteau <a href=\"mailto:denis.guicheteau@univ-tln.fr\" target=\"_blank\" rel=\"noopener\">denis.guicheteau@univ-tln.fr<\/a> qui travaille \u00e0 pr\u00e9sent dans ce laboratoire de recherche et que beaucoup d\u2019entre vous connaisse. Il aura la charge de faire le lien avec le secondaire \u00e0 partir de la rentr\u00e9e prochaine. De beaux projets en perspective !<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-40px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#0DA0C5&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb40px||||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb border_color_all=\u00a0\u00bb#0C71C3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #000080; font-size: 14pt;\">Actualit\u00e9s des labomaths<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-guillaume-Appolinaire-\u2013-Laurine-Jalliffier\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Lyc\u00e9e guillaume Appolinaire \u2013 Laurine Jalliffier<\/span><\/em><\/h3>\n<p><strong>Organisation de deux repr\u00e9sentations de Nobelles<\/strong> (Com\u00e9die des ondes) le jeudi 27 novembre : une le matin \u00e0 destination de 5 coll\u00e8ges des alentours et une l\u2019apr\u00e8s-midi pour 9 classes du lyc\u00e9e. Plusieurs disciplines ont pu s\u2019emparer du projet et de nombreuses initiatives de coll\u00e8gues ont \u00e9merg\u00e9 autour de la place des femmes dans la science.<\/p>\n<p><strong>Organisation d&rsquo;une r\u00e9union<\/strong> avec un des coll\u00e8ges du bassin pour r\u00e9fl\u00e9chir au <strong>renforcement de la liaison coll\u00e8ge\/lyc\u00e9e<\/strong>:<br \/>&#8211; Travailler les automatismes et le calcul mental.<br \/>&#8211; Participation \u00e0 la course aux nombres et faire un petit concours (modeste) fa\u00e7on course aux nombres entre les troisi\u00e8mes et les secondes.<br \/>&#8211; Faire travailler les \u00e9l\u00e8ves de seconde sur les attendus \u00e0 ma\u00eetriser pour la seconde afin de tutorer les \u00e9l\u00e8ves de troisi\u00e8me.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image aligncenter\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/n3ro2yzg07rsm4830bpz1p224.png\" alt=\"\" width=\"315\" height=\"167\"><\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-Mass\u00e9na-\u2013-Caroline-Chevalier\" class=\"\"><i class=\"fa fa-link\"><\/i><span style=\"color: #000080;\"><em>Labomaths Lyc\u00e9e Mass\u00e9na \u2013 Caroline Chevalier<\/em><\/span><\/h3>\n<p>Remise en place des <strong>inscriptions et pr\u00e9parations aux concours<\/strong> (rallye, olympiades).<br \/>Peut-\u00eatre la venue d\u2019un ancien \u00e9l\u00e8ve dans le cadre de <strong>\u201c1 scientifique, 1 classe, chiche\u201d avec INRIA<\/strong>.<\/p>\n<h3 id=\"Labomaths-Coll\u00e8ge-Genevoix-Toulon-\u2013-Dalia-Kasparoff\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Coll\u00e8ge Genevoix, Toulon \u2013 Dalia Kasparoff<\/span><\/em><\/h3>\n<p><strong>Cr\u00e9ation d\u2019un jeu de soci\u00e9t\u00e9 de la course aux nombres<\/strong> : les cartes questions sont les questions des \u00e9preuves de la courses aux nombres du cycle 3 et du cycle4.<br \/>Mme Leconte a une fois de plus cr\u00e9er un <strong>escape game<\/strong> spectaculaire sur le th\u00e8me de <strong>\u00ab\u00a0Alice au pays des merveilles\u00a0\u00bb<\/strong>.<\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-de-Lorgues-\u2013-Arnaud-Cabantous-et-Sophie-Jabot\" class=\"\"><i class=\"fa fa-link\"><\/i><span style=\"color: #000080;\"><em>Labomaths Lyc\u00e9e de Lorgues \u2013 Arnaud Cabantous et Sophie Jabot<\/em><\/span><\/h3>\n<ol>\n<li class=\"\"><strong>Concertation<\/strong> des enseignants (mercredi 12\/11 de 14h \u00e0 16h) : \u00e9changes sur les pratiques p\u00e9dagogiques et notamment sur les automatismes et les \u00e9preuves anticip\u00e9es en classe de premi\u00e8re pour le baccalaur\u00e9at.<br \/>Concertation pour mettre en place un soutien en seconde pour tous les \u00e9l\u00e8ves : utilisation de fiches-m\u00e9thode communes.<\/li>\n<li class=\"\"><strong>Biblioth\u00e8que d\u00e9di\u00e9e aux Math\u00e9matiques au CDI<\/strong>.<br \/>&nbsp;Achats en 2025 :<br \/>&#8211; BD : Pour une fraction de seconde.<br \/>&#8211; Math\u00e9opolis (2 tomes).<br \/>&#8211; Brochures sur les fractales, apprivoiser l\u2019infini, le nombre d\u2019or.<br \/>&#8211; Les El\u00e9ments de G\u00e9om\u00e9trie (conf\u00e9rence d\u2019Andr\u00e9 Deledicq).<br \/>&#8211; Le Th\u00e9or\u00e8me du Parapluie (Micka\u00ebl Launay).<br \/>&#8211; Histoire et l\u00e9gendes math\u00e9matiques (Catherine d\u2019Andrea).<br \/>&#8211; Installation d\u2019un grand panneau d\u2019affichage dans une salle et pr\u00e9paration de fiches plastifi\u00e9es sur des math\u00e9maticiens.<\/li>\n<li class=\"\"><strong>Concours Kangourou le jeudi 19 mars 2026<\/strong><br \/>&#8211; Course aux nombres.<br \/>&#8211; Inscription d\u2019une classe de seconde au concours CASTOR.<\/li>\n<li class=\"\"><strong>Pour faire progresser nos \u00e9l\u00e8ves<\/strong> : aides mises en place \u00e0 l\u2019internat, atelier r\u00e9ussite, tutorat avec \u00ab\u00a0<strong>\u00e9mENSip\u2019<\/strong>\u00a0\u00bb individualis\u00e9 en distanciel par les \u00e9tudiants en partenariat avec l\u2019ENS de Lyon.<br \/>Nous envisageons \u00e9galement de mettre en place un tutorat entre \u00e9l\u00e8ves de terminale et de seconde.<\/li>\n<li class=\"\"><strong>Maintenir un lien avec le Fablab du lyc\u00e9e<\/strong> :<br \/>&#8211; Fabrication de conique en bois.<br \/>&#8211; Astrolab science : \u00e0 venir <a href=\"https:\/\/www.astrolabe-science.fr\/coniques-dapollonius\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.astrolabe-science.fr\/coniques-dapollonius\/<\/a><br \/>&#8211; Conception et vente de mat\u00e9riel p\u00e9dagogique pour la compr\u00e9hension des d\u00e9cimaux et des fractions.<br \/>&#8211; Fractiq\u2019 : deux \u00e9tages de fractions qui D\u00e9cimaths : comprendre ce que permettent d\u2019aborder les fractions sup\u00e9rieures \u00e0 1. repr\u00e9sentent les dixi\u00e8mes et les centi\u00e8mes.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"md-image alignleft\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/y63xvmde6c8fwd05yrb0i2mhb.png\" alt=\"\" width=\"135\" height=\"169\">&nbsp; &nbsp; &nbsp; &nbsp; <img loading=\"lazy\" decoding=\"async\" class=\"md-image alignnone\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/dig6eazij2a3re2s8dl6b0q74.png\" alt=\"\" width=\"321\" height=\"187\"><\/li>\n<li class=\"\"><strong>Conf\u00e9rencier \u00e0 venir<\/strong><\/li>\n<li class=\"\"><strong>Actions en faveur de la r\u00e9ussite de nos \u00e9l\u00e8ves<\/strong>&nbsp;<br \/>&#8211; Pour favoriser l\u2019acc\u00e8s des filles aux fili\u00e8res de num\u00e9rique : intervention des femmes du campus num\u00e9rique de Lorgues.<br \/>&#8211; Pour pr\u00e9senter les diff\u00e9rentes fili\u00e8res des classes pr\u00e9paratoires : intervention des professeurs des CPGE des lyc\u00e9es du secteur.<\/li>\n<\/ol>\n<h3 id=\"Labomaths-Coll\u00e8ge-Bellevue-Beausoleil-\u2013-Naim-Benzebiba\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Coll\u00e8ge Bellevue, Beausoleil \u2013 Naim Benzebiba<\/span><\/em><\/h3>\n<p>En ce qui concerne le bilan du premier trimestre, il concerne essentiellement trois temps :<br \/>&#8211; <strong>Une sortie avec toutes les classes de 3\u00e8 pour assister \u00e0 la pi\u00e8ce Prof. Turing<\/strong> suivie d\u2019un travail sur le th\u00e9\u00e2tre en fran\u00e7ais et d\u2019un travail sur la cryptographie en math\u00e9matiques (sur le chiffrement affine avec utilisation du tableur).<br \/>&#8211; <strong>Une formation inter-degr\u00e9s<\/strong> fin novembre dans le but de poursuivre le travail entam\u00e9 l\u2019an dernier sur la manipulation dans le cadre de la r\u00e9solution de probl\u00e8mes (mod\u00e8le en barre et r\u00e9flexion autour d\u2019une progression coh\u00e9rente sur le cycle 3 essentiellement).<br \/>&#8211; <strong>Participation aux d\u00e9fis scientifiques<\/strong> (\u00e9quipe pavage avec Philippe Maisonobe, UCA et Tony Doremus, coll\u00e8ge Nucera, Nice).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image alignleft\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/f41pxn6nwpwkscu68mf5k58c3.png\" alt=\"\" width=\"260\" height=\"133\"><img loading=\"lazy\" decoding=\"async\" class=\"md-image alignleft\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/v59nvdg6tbztn8xrxp6ah5tka.png\" alt=\"\" width=\"218\" height=\"131\"><\/p>\n<h3>&nbsp;<\/h3>\n<h3>&nbsp;<\/h3>\n<h3>&nbsp;<\/h3>\n<h3>&nbsp;<\/h3>\n<h3 id=\"Labomaths-Coll\u00e8ge-la-Marquisanne-\u2013-Audrey-Damet-\u2013-Ariane-Scalisi-\u2013-Josselin-Einhorn\" class=\"\"><em><span style=\"color: #000080;\">Labomaths Coll\u00e8ge la Marquisanne \u2013 Audrey Damet \u2013 Ariane Scalisi \u2013 Josselin Einhorn<\/span><\/em><\/h3>\n<p>Nouvelle organisation pour l\u2019ann\u00e9e 2025-2026, Ariane Scalisi coordonnera les actions plut\u00f4t ax\u00e9es sur les 4eme\/3\u00e8me et Audrey Damet poursuivra les actions tourn\u00e9es vers les 6e\/5e. Le club math est toujours coordonn\u00e9 par Josselin Einhorn.<\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-Dumont-d\u2019Urville-Toulon-\u2013-Xavier-Pellegrin-\u2013-St\u00e9phane-Hamon\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Lyc\u00e9e Dumont d\u2019Urville, Toulon \u2013 Xavier Pellegrin \u2013 St\u00e9phane Hamon<\/span><\/em><\/h3>\n<p><strong><span style=\"font-size: 14pt;\">Projets d\u00e9j\u00e0 men\u00e9s :<\/span><br \/><\/strong>&#8211; Vendredi 5 d\u00e9cembre, demi journ\u00e9e \u201cElles bougent\u201d \u00e0 Dumont. (Projet dirig\u00e9 par une coll\u00e8gue documentaliste Mme Cabaud) Participation d\u2019un groupe d\u2019\u00e9l\u00e8ves (environ 12) du coll\u00e8ge Voltaire (LaboMaths Vincent Spielmann). Participation d\u2019environ 20 \u00e9l\u00e8ves de pr\u00e9pa et 120 du secondaire.<br \/>&#8211; Participation de Dumont d\u2019Urville (classes du secondaire) au prix Tangente des lyc\u00e9ens (g\u00e9r\u00e9 par Nathalie Falgui\u00e8res et Marion Castellani).<br \/>&#8211; Club\/atelier de maths hebdomadaire anim\u00e9 par N. Falgui\u00e8res et M. Castellani (soutien de maths, jeux, etc).<br \/>&#8211; Programm\u00e9, fin janvier 2026 : visite d\u2019\u00e9l\u00e8ves du coll\u00e8gue Voltaire en TP en pr\u00e9pa \u00e0 Dumont.<\/p>\n<p><strong><span style=\"font-size: 14pt;\">Projets en cours :<\/span><br \/><\/strong>&#8211; Organisation des 3 conf\u00e9rences de Jean Marc Ginoux \u00e0 Dumont. Possibilit\u00e9 aux personnes ext\u00e9rieures au lyc\u00e9e de s\u2019inscrire. Un lien sera disponible pour chaque conf\u00e9rence.<br \/>&#8211; Jeudi 29 janvier \u00e0 18h, pour la conf\u00e9rence n\u00b01 sur Jules Verne et la Science :<br \/>C\u2019est une passionnante conf\u00e9rence devant un public conquis, que le math\u00e9maticien et historien des sciences Jean-Marc Ginoux,a donn\u00e9 sur le contexte historique et scientifique, et sur la place des inventions, extraordinaires, de Jules Verne dans ses \u0153uvres.<br \/>&#8211; Jeudi 12 mars \u00e0 18h, pour la conf\u00e9rence n\u00b032 sur la place des femmes dans l\u2019histoire des sciences.<br \/><em>Un r\u00e9sum\u00e9 de la conf\u00e9rence:<\/em><br \/><em>Tout le monde a entendu parl\u00e9 de Marie Curie, premi\u00e8re femme de l\u2019histoire a avoir obtenu un prix Nobel, pour ses travaux sur la radioactivit\u00e9. Mais qui connait l\u2019importance des travaux de Th\u00e9ano de Crotone, philosophe et math\u00e9maticienne antique, \u00e9pouse du c\u00e9l\u00e8bre Pythagore, ou plus r\u00e9cemment de Rosalind Franklin, qui a jou\u00e9 un r\u00f4le crucial dans la mise en \u00e9vidence de la structure en double h\u00e9lice de l\u2019ADN au milieu du vingti\u00e8me si\u00e8cle ?<img loading=\"lazy\" decoding=\"async\" class=\"md-image aligncenter\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/znr905nckvw09nd7szpjwlpqp.png\" alt=\"\" width=\"132\" height=\"193\"><\/em><\/p>\n<p>&#8211; Jeudi 30 avril \u00e0 18h, pour la conf\u00e9rence n\u00b0 20 sur les traces de Galil\u00e9e.<br \/>&#8211; Visites, pr\u00e9sentations par des \u00e9l\u00e8ves (notamment filles) de pr\u00e9pa scientifiques dans les classes du secondaire, pour encourager le choix de sp\u00e9 maths (et sciences de fa\u00e7on g\u00e9n\u00e9rale) en 1ere et en terminale, et encourager l\u2019orientation en CPGE apr\u00e8s le bac. Binomes volontaires de pr\u00e9pa (1fille+1garcon) d\u00e9j\u00e0 identifi\u00e9s, avec leurs dispos hebdomadaires.<\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-Carnot-Cannes-\u2013-Jonas-L\u00e9vy\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Lyc\u00e9e Carnot Cannes \u2013 Jonas L\u00e9vy<\/span><\/em><\/h3>\n<p>Pr\u00e9paration d\u2019un tr\u00e8s gros programme pour la semaine des maths.<br \/>Au programme: escape game 2.0 \/ jeu de piste autour des grands math\u00e9maticien \/ conf\u00e9rences \/ concours de calcul mental sous la forme d\u2019un jeu t\u00e9l\u00e9 (Sigma calcul challenge)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/fu44irc9cqnwkea2gzvnf46c7.png\" alt=\"\" width=\"152\" height=\"220\">&nbsp;<img loading=\"lazy\" decoding=\"async\" class=\"md-image\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/vo0tviwsbvvwr2moabm1t2yc9.png\" alt=\"\" width=\"152\" height=\"220\"> <img loading=\"lazy\" decoding=\"async\" class=\"md-image\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/z6fembpdzaut3dzrbeo74vuhr.png\" alt=\"\" width=\"151\" height=\"219\"><\/p>\n<h3 id=\"Labomaths-Coll\u00e8ge-Alphonse-Daudet-Nice-\u2013-Khadija-Bouazzaoui\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Coll\u00e8ge Alphonse Daudet, Nice \u2013 Khadija Bouazzaoui<\/span><\/em><\/h3>\n<p><span style=\"font-size: 14pt;\"><strong>Voici le bilan des actions men\u00e9es <\/strong>:<\/span><br \/>&#8211; Rentr\u00e9e Labomath le 09\/10\/2025 avec une pr\u00e9sentation de Val\u00e9rie Lemesle de diff\u00e9rentes actions possibles en math\u00e9matiques;<br \/>&#8211; F\u00eate de la Science: Faites de la science \u00e0 la f\u00eate de la science !<br \/>&#8211; Concours Castor Informatique (liaison CM2\/6e) ;<br \/>&#8211; Cin\u00e9science 5e : une classe de 5e a assist\u00e9 \u00e0 la projection en avant-premi\u00e8re du film Plan\u00e8tes ; les \u00e9l\u00e8ves ont pu \u00e9changer avec une assistante de r\u00e9alisation du film et un astrophysicien.<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Et celles pr\u00e9vues prochainement :<\/strong><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Semaine des math\u00e9matiques&nbsp;<br \/><\/strong>Concours Calcul@TICE (liaison CM2\/6e).<br \/>Concours d\u2019\u00e9nigmes.<br \/>Concours Kangourou.<br \/>Course aux Nombres.<br \/>Visite de l\u2019Espace de l\u2019Art Concret (Maths&amp;Art).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Semaine de la presse et des m\u00e9dias&nbsp;<br \/><\/strong>&nbsp; Intervention de l\u2019INSEE en classe de 6e.<br \/>&nbsp; EDUCFI en 4e<br \/>&nbsp; Visite de la Maison de l\u2019Intelligence Artificielle<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Autres p\u00e9riodes<\/strong>&nbsp;<br \/>&nbsp; ProfTuring.<br \/>&nbsp; Projet scrabble (liaison CM2\/6e).<br \/>&nbsp; Liaison 3e\/2nde.<br \/>&nbsp; Rallye math\u00e9matiques (liaison CM2\/6e).<br \/>&nbsp; Ateliers sur les probabilit\u00e9s et la trigonom\u00e9trie en 3e.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Pour le mat\u00e9riel: conception de sacs myst\u00e8re \u00e0 partir de solides fabriqu\u00e9s au Fabrikathon.<br \/>Et pour les clubs : Club Kangourou des Maths pour pr\u00e9parer le concours, Club \u00c9checs, Club Scrabble (qui devront \u00eatre mis prochainement sur Adage).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/pdbjur9sxgj5y8lqwbmc7ghcz.png\" alt=\"\" width=\"192\" height=\"103\"> <img loading=\"lazy\" decoding=\"async\" class=\"md-image\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/qrj1uqjfo1ldz6pdwan0ru63c.png\" alt=\"\" width=\"193\" height=\"104\"> <img loading=\"lazy\" decoding=\"async\" class=\"md-image\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/iua1je2s0ye976k8v10qjd8j9.png\" alt=\"\" width=\"192\" height=\"103\"> <img loading=\"lazy\" decoding=\"async\" class=\"md-image alignnone\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/x2zyui8mgil8whrss5a3jtcw6.png\" alt=\"\" width=\"190\" height=\"102\"><\/p>\n<h3 id=\"Labomaths-Coll\u00e8ge-Jules-Verne-\u2013-Ang\u00e9lique-Videau\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Coll\u00e8ge Jules Verne \u2013 Ang\u00e9lique Videau<\/span><\/em><\/h3>\n<p>Le labomaths du coll\u00e8ge Jules Verne a \u00e9t\u00e9 d\u00e9velopp\u00e9 autour de 4 axes : les \u00e9changes entre le 1er degr\u00e9 et le 2nd degr\u00e9 , des projets avec le sup\u00e9rieur UniCA et CNES, le passeport EDUCFI et le plan Filles Maths.<\/p>\n<p><strong><span style=\"font-size: 14pt;\">Le bilan des actions men\u00e9es :<\/span><br \/><\/strong><strong>Participation \u00e0 l\u2019\u00e9dition 2026 au Fabrikathon p\u00e9dagogique au Mathemarium<br \/><\/strong>Deux professeures du coll\u00e8ge Mme Fraticelli et Mme Videau ont particip\u00e9 \u00e0 un moment convivial entre professeurs de technologie et de math\u00e9matiques. La mission \u00e9tait de fabriquer du mat\u00e9riel p\u00e9dagogique \u00e0 destination des \u00e9l\u00e8ves. Ce rendez-vous a eu lieu les mercredi 7 janvier et jeudi 8 janvier 2026.<br \/><a href=\"https:\/\/mathemarium.fr\/Photos-Fabrikathon-Pedagogique-a-Nice.html\" target=\"_blank\" rel=\"noopener\">https:\/\/mathemarium.fr\/Photos-Fabrikathon-Pedagogique-a-Nice.html<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image aligncenter\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/s90whjzkuyyq1kc0lw5rc7li1.png\" alt=\"\" width=\"209\" height=\"124\"><strong>Plan Filles Maths&nbsp;<br \/>-&gt;<\/strong>Une semaine autour de la journ\u00e9e internationale des femmes et des filles de sciences. Cette journ\u00e9e a eu lieu le mercredi 11 f\u00e9vrier 2026.<br \/>Trois rendez-vous importants ont eu lieu au Coll\u00e8ge Jules Verne&nbsp;:<br \/>&#8211; Le mardi 10 f\u00e9vrier 2026 , diff\u00e9rentes classes du coll\u00e8ge ont particip\u00e9 \u00e0 \u00ab DM ta scientifique \u00bb organis\u00e9 par l\u2019universit\u00e9 C\u00f4te d\u2019Azur.<br \/><a href=\"https:\/\/scienceazur.univ-cotedazur.fr\/dm-une-scientifique\" target=\"_blank\" rel=\"noopener\">https:\/\/scienceazur.univ-cotedazur.fr\/dm-une-scientifique<\/a><br \/>Les \u00e9l\u00e8ves ont beaucoup aim\u00e9 \u00e9changer. Certains \u00e9l\u00e8ves ont m\u00eame continu\u00e9 chez eux le soir. Une belle exp\u00e9rience.<br \/>&#8211; Le mercredi 11 f\u00e9vrier 2026, de 10h \u00e0 12h , deux classes du coll\u00e8ge ont eu la chance de rencontrer des femmes et filles ing\u00e9nieures ou en devenir. Deux femmes ing\u00e9nieures chez Schneider Electric, une femme ing\u00e9nieure chez Amadeus et une \u00e9tudiante \u00e0 Polytech Nice Sophia ainsi qu\u2019un repr\u00e9sentant d\u2019IESF sont venus expliquer le m\u00e9tier d\u2019ing\u00e9nieure et les \u00e9tudes correspondantes. Mme Marzourk professeure de la fili\u00e8re STI2D au lyc\u00e9e Renoir de Cagnes sur mer est venue pr\u00e9sent\u00e9e sa mati\u00e8re aux \u00e9l\u00e8ves pr\u00e9sents. (Filles et gar\u00e7ons)<br \/>&#8211; Le vendredi 13 f\u00e9vrier 2026, les \u00e9l\u00e8ves de 4e3 impliqu\u00e9s dans le projet CHLORiss du CNES ont assist\u00e9 en diff\u00e9r\u00e9 au d\u00e9part de Sophie Adenot. <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fichier:Leur_G%C3%A9n%C3%A9ration_%C3%89galit%C3%A9_-_portrait_de_Sophie_Adenot.webm\" target=\"_blank\" rel=\"noopener\">https:\/\/fr.wikipedia.org\/wiki\/Fichier:Leur_G\u00e9n\u00e9ration_\u00c9galit\u00e9_-_portrait_de_Sophie_Adenot.webm<\/a>.<br \/>Le projet consistera \u00e0 faire pousser en m\u00eame temps que Sophie Adenot diff\u00e9rentes plantes et d\u2019analyser les r\u00e9sultats obtenus. La classe de 4e 3 \u00e9tant \u00e9galement inscrite au programme \u00ab Coll\u00e9giens au cin\u00e9ma \u00bb par Mme Akar, ils auront la possibilit\u00e9 de visionner le film Proxima sur la vie d\u2019une astronaute. De ces deux exp\u00e9riences, ils pourront travailler sur le m\u00e9tier d\u2019astronaute et le valoriser aupr\u00e8s des filles ainsi que des gar\u00e7ons. Les \u00e9l\u00e8ves pourront ainsi d\u00e9couvrir diff\u00e9rents m\u00e9tiers autour de l\u2019astrophysique.<\/p>\n<p><strong><span style=\"font-size: 14pt;\">Les actions pr\u00e9vues prochainement :<\/span><br \/><\/strong><strong>Les d\u00e9fis scientifiques \u00e9l\u00e8ves<\/strong><br \/>Une classe de 5e est inscrite aux d\u00e9fis scientifiques suivant :<br \/><a href=\"https:\/\/scienceazur.univ-cotedazur.fr\/defis-scientifiques\/comment-calculait-on-avant\" target=\"_blank\" rel=\"noopener\">https:\/\/scienceazur.univ-cotedazur.fr\/defis-scientifiques\/comment-calculait-on-avant<\/a> les-ordinateurs-et-les-calculatrices<br \/>Le d\u00e9fi a commenc\u00e9 en janvier 2026 et se terminera par une journ\u00e9e \u00e0 l\u2019universit\u00e9 de Valrose le jeudi 7 mai 2026 pour les \u00e9l\u00e8ves. Ils devront pr\u00e9senter devant l\u2019ensemble des \u00e9tablissements \u00e9coles\/coll\u00e8ges\/lyc\u00e9es leurs travaux.<br \/>Tout au long de ce projet, ils seront accompagn\u00e9s par Marc Monticelli (Ing\u00e9nieur de recherche au LJAD).&nbsp;\u2022 Les d\u00e9fis scientifiques enseignants<br \/>Deux professeures du coll\u00e8ge sont inscrites au d\u00e9fi scientifique suivant : Il faut que tu respires et \u00e7a c\u2019est math\u00e9matiques !<br \/>Chercheur encadrant : Benjamin Mauroy, directeur de recherche CNRS, LJAD madame Fraticelli et madame Videau se sont inscrites \u00e0 ce d\u00e9fi. Une \u00e9quipe f\u00e9minine et motiv\u00e9e pour \u00e9tudier le mod\u00e8le math\u00e9matique de la respiration. Elles ont pour mission de comprendre comment l\u2019organisme des mammif\u00e8res ing\u00e8re l\u2019ozone et de d\u00e9terminer les cons\u00e9quences sur la biodiversit\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image aligncenter\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/d41pkv586fw0ajvmttp5u1rqy.png\" alt=\"\" width=\"208\" height=\"123\"><\/p>\n<p><strong>EDUCFI : Passeport et projet Anglais\/Maths<\/strong><br \/>&#8211; Passeport EDUCFI niveau 4e. En mars 2026 aura lieu la semaine de l\u2019\u00e9ducation financi\u00e8re, \u00e0 cette occasion, tous les \u00e9l\u00e8ves de 4e du coll\u00e8ge Jules Verne passeront le passeport EDUCFI.<br \/>&#8211; Projet EDUCFI Anglais\/Maths Depuis octobre 2025, deux classes de 4e (4e1 et 4e3) travaillent sur un projet interdisciplinaire Anglais Math\u00e9matiques. Madame Akar (professeure d\u2019Anglais) et madame Videau (professeure de math\u00e9matiques) font travailler leur \u00e9l\u00e8ves sur l\u2019\u00e9ducation financi\u00e8re en proposant une comparaison entre le syst\u00e8me bancaire et financier fran\u00e7ais et celui des Etats-Unis.<br \/>A cette occasion, les \u00e9l\u00e8ves de 4e3 participeront \u00e0 une rencontre avec les r\u00e9f\u00e9rents de la Banque de France dont monsieur K\u00e9vin MONFEUGAS en pr\u00e9sence de Mme Fiol ,IA IPR de math\u00e9matiques et madame St\u00e9phanie Gilabert r\u00e9f\u00e9rente acad\u00e9mique. Cet \u00e9v\u00e9nement aura lieu lors de la semaine nationale EDUCFI du 16 mars au 22 mars 2026.<\/p>\n<p><strong>Semaine des math\u00e9matiques<br \/><\/strong>Exposition sur les math\u00e9maticiennes dans le coll\u00e8ge.<br \/>De d\u00e9cembre 2025 \u00e0 mars 2026, 5 classes du coll\u00e8ge sur 3 niveaux travaillent sur des expos\u00e9s sur les math\u00e9maticiennes internationales souvent invisibilis\u00e9es. A partir de ces expos\u00e9s, ils proposeront une exposition lors de la semaine des math\u00e9matiques sur les math\u00e9maticiennes \u00e0 l\u2019ensemble du coll\u00e8ge. Ils parleront \u00e9galement des 72 femmes scientifiques fran\u00e7aises dont le nom sera prochainement inscrits sur la Tour Eiffel.<br \/><a href=\"https:\/\/www.femmesetsciences.fr\/news\/les-noms-des-72-femmes-pour-la-tour-eiffel-ont-%C3%A9t%C3%A9-r%C3%A9v%C3%A9l%C3%A9\" target=\"_blank\" rel=\"noopener\">https:\/\/www.femmesetsciences.fr\/news\/les-noms-des-72-femmes-pour-la-tour-eiffel-ont-\u00e9t\u00e9-r\u00e9v\u00e9l\u00e9<\/a><br \/>&#8211; La course aux nombres sur tous les niveaux et toutes les classes.<br \/>&#8211; Peut-\u00eatre d\u2019autres petits projets \u00e0 venir \u2026<\/p>\n<p><strong>Club Echecs<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image alignleft\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/qerapkl5sz29wfcr3oy4i4rxr.png\" alt=\"\" width=\"108\" height=\"144\"><\/p>\n<p>Tous les lundis midis de 12h25 \u00e0 13h15, les \u00e9l\u00e8ves du coll\u00e8ge qui le souhaitent ont la possibilit\u00e9s de s\u2019initier ou de se confronter autour des \u00e9checs. Ce club anim\u00e9 par Monsieur Pellero a un vif succ\u00e8s aupr\u00e8s de nos coll\u00e9giens.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ce qui est \u00e0 venir&nbsp;:<br \/>&#8211; Collaboration avec le premier degr\u00e9 , lors des \u00e9changes CM2 &#8211; 6e en juin 2026 autour de la course aux nombres et autres ateliers.<br \/>De futurs projets en pr\u00e9paration autour de l\u2019\u00e9galit\u00e9 filles gar\u00e7ons, de formations, de travaux math\u00e9matiques en anglais en primaire, EDUCFI, \u2026<\/p>\n<p>&#8211; Collaboration avec le lyc\u00e9e Renoir autour de la s\u00e9rie STI2D.<\/p>\n<h3 id=\"Labomaths-R\u00e9seau-Dettloff\" class=\"\"><i class=\"fa fa-link\"><\/i><span style=\"color: #000080;\"><em>Labomaths R\u00e9seau Dettloff<\/em><\/span><\/h3>\n<p>Formation autour de l\u2019oral ?<\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-Manouchian-\u2013-Marie-Bouchacourt-\u2013-Olivier-Cavallo\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Lyc\u00e9e Manouchian \u2013 Marie Bouchacourt \u2013 Olivier Cavallo<\/span><\/em><\/h3>\n<p>Tourn\u00e9 autout de la liaison coll\u00e8ge-lyc\u00e9e: une action de formation pr\u00e9vu le jeudi 22 janvier avec 14 coll\u00e8gues des coll\u00e8ges environnant !<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h3 id=\"Labomaths-\u2013-St\u00e9phanie-Gilbert-\u2013-Farid-Bejaoui\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths \u2013 St\u00e9phanie Gilbert \u2013 Farid Bejaoui<\/span><\/em><\/h3>\n<p><strong>Stat\u2019Acad\u00e9mie : une belle aventure statistique pour les \u00e9l\u00e8ves du Luc et du Cannet-des-Maures<br \/><\/strong>Dans le cadre du concours Stat\u2019Acad\u00e9mie, con\u00e7u et organis\u00e9 en partenariat avec l\u2019INSEE Provence-Alpes-C\u00f4te d\u2019Azur, deux classes de sixi\u00e8me du coll\u00e8ge Pierre-de-Coubertin du Luc ainsi que deux classes de l\u2019\u00e9cole Denis-Tissot du Cannet-des-Maures (une classe de CM2 et une classe de CM1\/CM2) ont particip\u00e9 \u00e0 un projet p\u00e9dagogique autour de la d\u00e9couverte et de l\u2019exploitation des donn\u00e9es statistiques.<strong>&nbsp;<\/strong><\/p>\n<p><strong>Une premi\u00e8re phase de r\u00e9flexion et d\u2019analyse<\/strong><\/p>\n<p>Lors de la premi\u00e8re phase, organis\u00e9e \u00e0 la fin du mois de mars, les \u00e9l\u00e8ves ont r\u00e9pondu individuellement \u00e0 un questionnaire \u00e9labor\u00e9 \u00e0 partir de donn\u00e9es statistiques locales, d\u00e9partementales et r\u00e9gionales. Ils ont ainsi \u00e9t\u00e9 amen\u00e9s \u00e0 analyser et interpr\u00e9ter des informations portant sur des th\u00e8mes vari\u00e9s tels que :<br \/>&nbsp; &#8211; les sports pratiqu\u00e9s dans diff\u00e9rentes r\u00e9gions ;<br \/>&nbsp; &#8211; les pr\u00e9noms donn\u00e9s aux enfants ;<br \/>&nbsp; &#8211; le logement des familles ;<br \/>&nbsp; &#8211; la gestion des d\u00e9chets ;<br \/>&nbsp; &#8211; la r\u00e9partition des \u00e2ges de la population ;<br \/>&nbsp; &#8211; le temps consacr\u00e9 aux \u00e9crans.<\/p>\n<p>Cette activit\u00e9 leur a permis de d\u00e9velopper leurs comp\u00e9tences en lecture de donn\u00e9es et en raisonnement statistique.<strong>&nbsp;<\/strong><\/p>\n<p><strong>Une deuxi\u00e8me phase plac\u00e9e sous le signe de la coop\u00e9ration<br \/><\/strong>\u00c0 la mi-mai, les classes participantes se sont r\u00e9unies pour la deuxi\u00e8me phase du concours. R\u00e9partis en groupes, les \u00e9l\u00e8ves ont r\u00e9alis\u00e9 des affiches pr\u00e9sentant les r\u00e9sultats d\u2019un questionnaire consacr\u00e9 aux activit\u00e9s extrascolaires. Ce travail collaboratif a mobilis\u00e9 leurs capacit\u00e9s d\u2019analyse, de synth\u00e8se et de communication visuelle.<strong>&nbsp;<\/strong><\/p>\n<p><strong>Des ateliers et une c\u00e9r\u00e9monie de remise des r\u00e9compenses<br \/><\/strong>D\u00e9but juin, des ateliers anim\u00e9s par les \u00e9quipes de l\u2019INSEE ont permis aux \u00e9l\u00e8ves d\u2019approfondir leur d\u00e9couverte de la statistique avant le moment tant attendu : la remise des r\u00e9compenses, venue saluer l\u2019investissement et le travail de chacun.<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>&nbsp;<\/strong><strong>Palmar\u00e8s g\u00e9n\u00e9ral<\/strong><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p><strong>Phase 1 : questionnaire sur les donn\u00e9es d\u00e9partementales et r\u00e9gionales<\/strong><\/p>\n<p><u>Premier prix Sixi\u00e8me :<\/u> 1 \u00e9l\u00e8ve<\/p>\n<p><u>Premier prix CM2 (ex \u00e6quo) :<\/u> 2 \u00e9l\u00e8ves ex aequo<\/p>\n<p><u>Premier prix CM1 :<\/u> 1 \u00e9l\u00e8ve<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p><strong>Phase 2&nbsp;: Concours d\u2019affiches<\/strong><\/p>\n<p><u>Premier prix :<\/u> affiche r\u00e9alis\u00e9e par 3 \u00e9l\u00e8ves de CM2 et 2 \u00e9l\u00e8ves de 6eme<\/p>\n<p><u>Deuxi\u00e8me prix :<\/u> affiche r\u00e9alis\u00e9e par 3 \u00e9l\u00e8ves de CM2 et 2 \u00e9l\u00e8ves de 6eme<\/p>\n<p><u>Troisi\u00e8me prix :<\/u> affiche r\u00e9alis\u00e9e par 2 \u00e9l\u00e8ves de CM2 et 2 \u00e9l\u00e8ves de 6eme<\/p>\n<p><u>Quatri\u00e8me prix (ex \u00e6quo) :<\/u> chaque affiche a \u00e9t\u00e9 r\u00e9alis\u00e9e par 1 \u00e9l\u00e8ve de CM1, 1 \u00e9l\u00e8ve de CM2 et 2 \u00e9l\u00e8ves de 6eme<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Cette premi\u00e8re \u00e9dition de Stat\u2019Acad\u00e9mie s\u2019est achev\u00e9e dans une ambiance chaleureuse autour d\u2019un go\u00fbter convivial r\u00e9unissant \u00e9l\u00e8ves, enseignants et partenaires.<br \/>Les professeurs Mme Lopez M\u00e9lodie (CM1-CM2), Mme Daniel Julie (6\u00e8), Mme Gilbert St\u00e9phanie (6\u00e8) et M. Otto-Bruc Julian (CM2) remercient tout particuli\u00e8rement les personnels de l\u2019INSEE Provence-Alpes-C\u00f4te d\u2019Azur pour le partenariat cr\u00e9\u00e9 et leur implication dans ce projet, et adressent leurs plus sinc\u00e8res f\u00e9licitations \u00e0 l\u2019ensemble des participants et des laur\u00e9ats pour la qualit\u00e9 de leur engagement.<br \/>Cot\u00e9 club de maths, Barbara Baryga-Giraud anime toujours un club bridge et Benjamin Raybaud un club informatique.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00a0\u00bb14605,14606,14607,14608,14609,14610,14611&Prime; show_title_and_caption=\u00a0\u00bboff\u00a0\u00bb show_pagination=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_gallery][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h3 id=\"Labomaths-Lyc\u00e9e-Simone-Veil--Coll\u00e8ge-L\u2019\u00c9ganaude-Valbonne--Biot-\u2013-C\u00e9dric-Gourjon--Sylvain-Etienne\" class=\"\"><em><span style=\"color: #000080;\">Labomaths Lyc\u00e9e Simone Veil \/ Coll\u00e8ge L\u2019\u00c9ganaude, Valbonne \/ Biot \u2013 C\u00e9dric Gourjon \/ Sylvain Etienne<\/span><\/em><\/h3>\n<p>Actions de formation pour les liaisons coll\u00e8ge-lyc\u00e9e \/ premier degr\u00e9-coll\u00e8ge (probabilit\u00e9 \u2013 formation en f\u00e9vrier). Concours d\u2019activit\u00e9 mentale au coll\u00e8ge de l\u2019Eganaude<\/p>\n<h3 id=\"Labomaths-Coll\u00e8ge-Beltrame-P\u00e9ogomas-\u2013-Isabelle-Hubert\" class=\"\"><i class=\"fa fa-link\"><\/i><em><span style=\"color: #000080;\">Labomaths Coll\u00e8ge Beltrame, P\u00e9ogomas \u2013 Isabelle Hubert<\/span><\/em><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"md-image aligncenter\" src=\"https:\/\/minio.apps.education.fr\/codimd-prod\/uploads\/lasqr2yr1dyzhtoub5pnlp31k.png\" alt=\"\" width=\"439\" height=\"317\"><\/p>\n<ul>\n<li class=\"\">Enigmes Halloween et \u00e9nigmes No\u00ebl<\/li>\n<li class=\"\">Des Escape Game pr\u00e9vus dont un sur le th\u00e8me de la famille (niveau 5\u00e8me -4\u00e8me).<\/li>\n<li class=\"\">Des \u201csets de table avec \u00e9galit\u00e9s\u201d seront propos\u00e9s au moment du menu autour de Pi.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#0DA0C5&Prime; text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb border_color_all=\u00a0\u00bb#0C71C3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2 id=\"PerpectivesActions-pour-le-2e-semestre\" class=\"\" style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #000080;\">Perpectives\/Actions pour le 2e semestre<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<ul>\n<li class=\"\">Semaine des maths ? Id\u00e9es ? Th\u00e8me les \u00c9galit\u00e9s<br \/>Des id\u00e9es autour de l\u2019\u00e9galit\u00e9 filles-gar\u00e7ons bien sur mais pas que ! \u00c0 r\u00e9flechir sur des actions communes? En lien avec les ateliers du Mathemarium? Le cin\u00e9ma? Dehors?<\/li>\n<\/ul>\n<ul>\n<li class=\"\">la page officielle avec le th\u00e8me et les dates pour cette ann\u00e9e<br \/><a href=\"https:\/\/eduscol.education.fr\/3493\/semaine-des-mathematiques\" target=\"_blank\" rel=\"noopener\">https:\/\/eduscol.education.fr\/3493\/semaine-des-mathematiques<\/a><\/li>\n<li class=\"\">des id\u00e9es de l\u2019acad\u00e9mie de Nice<br \/><a href=\"https:\/\/digipad.app\/p\/649063\/7e36970ee659e\" target=\"_blank\" rel=\"noopener\">https:\/\/digipad.app\/p\/649063\/7e36970ee659e<\/a><\/li>\n<li class=\"\">des id\u00e9es de l\u2019acad\u00e9mie de Bordeaux<br \/><a href=\"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/semaine-des-maths\/ressources\/\" target=\"_blank\" rel=\"noopener\">https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/semaine-des-maths\/ressources\/<\/a><\/li>\n<li class=\"\">des id\u00e9es de l\u2019acad\u00e9mie de Bordeaux (avec la grande lessive que j\u2019aime bcp!)<br \/><a href=\"https:\/\/mathematiques.ac-normandie.fr\/SEMAINE-DES-MATHEMATIQUES-2026\" target=\"_blank\" rel=\"noopener\">https:\/\/mathematiques.ac-normandie.fr\/SEMAINE-DES-MATHEMATIQUES-2026<\/a><\/li>\n<li class=\"\">des ressources (\u00e0 venir?) de l\u2019apmep<br \/><a href=\"https:\/\/www.apmep.fr\/La-Semaine-des-mathematiques-2026\" target=\"_blank\" rel=\"noopener\">https:\/\/www.apmep.fr\/La-Semaine-des-mathematiques-2026<\/a><\/li>\n<li class=\"\">un webinaire de canop\u00e9 le 4 f\u00e9vrier \u00e0 17h<br \/><a href=\"https:\/\/www.canotech.fr\/s\/38371\/des-activites-pour-jouer-la-semaine-des-mathematiques-en-classe?thematique=84\" target=\"_blank\" rel=\"noopener\">https:\/\/www.canotech.fr\/s\/38371\/des-activites-pour-jouer-la-semaine-des-mathematiques-en-classe?thematique=84<\/a><\/li>\n<li class=\"\">des id\u00e9es de films Th\u00e9or\u00e8me de Marguerite \/ Les femmes de l\u2019ombre<br \/>une plateforme pour les trouver l\u00e9galement Zero de conduite<br \/><a href=\"https:\/\/www.zerodeconduite.net\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.zerodeconduite.net\/<\/a><br \/>\ud83d\udc49Il y a beaucoup de ressources p\u00e9dagogiques sur ce site. N\u2019h\u00e9sitez pas \u00e0 vous cr\u00e9er un compte pour pouvoir y acc\u00e9der<br \/>Ici par exemple sur le th\u00e9or\u00e8me de Marguerite<br \/><a href=\"https:\/\/www.zerodeconduite.net\/system\/files\/document\/letheoremedemarguerite_dp.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.zerodeconduite.net\/system\/files\/document\/letheoremedemarguerite_dp.pdf<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/actualites-des-labomaths-de-lacademie-de-nice-2e-semestre-juillet-2025\/\u00a0\u00bb button_text=\u00a0\u00bbActualit\u00e9s des labomaths de l\u2019acad\u00e9mie de Nice 2e semestre &#8211; Juillet 2025&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/actualites-du-premier-semestre-des-labomaths-et-clubmaths-de-lacademie-janvier-2025\/\u00a0\u00bb button_text=\u00a0\u00bb Actualit\u00e9s des labomaths de l\u2019acad\u00e9mie de Nice Premier semestre \u2013 Janvier 2025&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-actualites-des-labomaths\/\u00a0\u00bb button_text=\u00a0\u00bbLes actualit\u00e9s des labomaths &#8211; 1er trimestre 2023\/2024&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-actualites-des-labomaths-2e-trimestre-2023-2024\/\u00a0\u00bb button_text=\u00a0\u00bbLes actualit\u00e9s des labomaths &#8211; 2e trimestre 2023\/2024&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-actualites-des-labomaths-3e-trimestre-2023-2024\/\u00a0\u00bb button_text=\u00a0\u00bbLes actualit\u00e9s des labomaths &#8211; 3e trimestre 2023\/2024&Prime; button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/category\/actualites-des-labomaths\/\u00a0\u00bb button_text=\u00a0\u00bbActualit\u00e9s des labomaths &#8211; Archives\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#0C71C3&Prime; custom_margin=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les labomaths<a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-labomaths-de-lacademie-de-nice-2025-2026\/' class='small-button smallblue'>Les labomaths &#8211; c&rsquo;est qui ?<\/a> <a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/laboratoires-et-clubs\/\/\/' class='small-button smallblue'>Actualit\u00e9s des labomaths<\/a>Les clubs maths<a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-clubs-maths-de-lacademie-de-nice-2025-2026\/' class='small-button smallblue'>Les clubs maths c&rsquo;est qui ?<\/a> <a href='https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/actualites-des-clubs-de-maths-de-lacademie\/' class='small-button smallblue'>Actualit\u00e9s des clubs<\/a> &nbsp; Actualit\u00e9s des labomaths de l\u2019acad\u00e9mie de Nice 1er semestre 2025-2026Animation des labomaths et des clubs maths de l\u2019acad\u00e9mie &#8211; 2026Compte rendu r\u00e9union du 15 janvier \u2013 Imath Toulon 32 [&hellip;]<\/p>\n","protected":false},"author":202,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-14868","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"admin","author_link":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/author\/opilorget\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Les labomaths[button link=\"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-labomaths-de-lacademie-de-nice-2025-2026\/\"]Les labomaths - c'est qui ?[\/button] [button link=\"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/laboratoires-et-clubs\/\/\/\"]Actualit\u00e9s des labomaths[\/button]Les clubs maths[button link=\"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/les-clubs-maths-de-lacademie-de-nice-2025-2026\/\"]Les clubs maths c'est qui ? [\/button] [button link=\"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/actualites-des-clubs-de-maths-de-lacademie\/\"]Actualit\u00e9s des clubs[\/button] &nbsp; Actualit\u00e9s des labomaths de l\u2019acad\u00e9mie de Nice 1er semestre 2025-2026Animation des labomaths et des clubs maths de l\u2019acad\u00e9mie - 2026Compte rendu r\u00e9union du 15 janvier \u2013 Imath Toulon 32\u2026","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/pages\/14868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/users\/202"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/comments?post=14868"}],"version-history":[{"count":2,"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/pages\/14868\/revisions"}],"predecessor-version":[{"id":14871,"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/pages\/14868\/revisions\/14871"}],"wp:attachment":[{"href":"https:\/\/www.pedagogie.ac-nice.fr\/mathematiques\/wp-json\/wp\/v2\/media?parent=14868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}